{"id":64817,"date":"2025-12-25T09:53:46","date_gmt":"2025-12-25T08:53:46","guid":{"rendered":"https:\/\/cp-hotline.com\/?page_id=64817"},"modified":"2026-05-13T11:15:30","modified_gmt":"2026-05-13T09:15:30","slug":"detska-mozkova-obrna","status":"publish","type":"page","link":"https:\/\/cp-hotline.com\/cs\/zerebralparese\/","title":{"rendered":"CP"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"64817\" class=\"elementor elementor-64817\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6ba3d e-flex e-con-boxed e-con e-parent\" data-id=\"8b6ba3d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-99f8eaf e-con-full e-flex e-con e-child\" data-id=\"99f8eaf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4b8eb18 e-con-full e-flex e-con e-child\" data-id=\"4b8eb18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b30f6d0 elementor-widget elementor-widget-image\" data-id=\"b30f6d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cp-hotline.com\/cs\/kontakt\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/elementor\/thumbs\/zerebralparese-kind-mutter-rollstuhl-verstehen-scaled-rnchn8cf1rpwsobqbdt7befejjzsatw9cp9vqhsw4k.jpg\" title=\"\u0160\u0165astn\u00e1,matka,obj\u00edmaj\u00edc\u00ed,jej\u00ed,syn,s,mozkovou,obrnou,na,invalidn\u00edm,voz\u00edku\" alt=\"\u0160\u0165astn\u00e1,matka,obj\u00edmaj\u00edc\u00ed,jej\u00ed,syn,s,mozkovou,obrnou,na,invalidn\u00edm,voz\u00edku\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ab4a57 e-con-full e-flex e-con e-child\" data-id=\"2ab4a57\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ecb9a9 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7ecb9a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Porozum\u011bn\u00ed CEREBR\u00c1LN\u00cd PAR\u00c9ZE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4758a0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e4758a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/cp-hotline.com\/cs\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktujte n\u00e1s pro v\u00edce informac\u00ed!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83d7521 e-con-full e-flex e-con e-child\" data-id=\"83d7521\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf4e31 elementor-widget elementor-widget-heading\" data-id=\"bbf4e31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">P\u0159\u00ed\u010diny ZEREBRALPARESIS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-737b9d9 elementor-widget elementor-widget-text-editor\" data-id=\"737b9d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u011btsk\u00e1 mozkov\u00e1 obrna je zp\u016fsobena <strong>Po\u0161kozen\u00ed ur\u010dit\u00fdch oblast\u00ed mozku<\/strong>, kter\u00e9 se pou\u017e\u00edvaj\u00ed k \u0159\u00edzen\u00ed <strong>Pohyb, dr\u017een\u00ed t\u011bla a svalov\u00e9 nap\u011bt\u00ed<\/strong> jsou zodpov\u011bdn\u00e9. K tomuto po\u0161kozen\u00ed doch\u00e1z\u00ed <strong>b\u011bhem t\u011bhotenstv\u00ed, b\u011bhem porodu nebo kr\u00e1tce po porodu.<\/strong> kdy\u017e se mozek st\u00e1le vyv\u00edj\u00ed.<\/p><p>Mo\u017en\u00e9 p\u0159\u00ed\u010diny jsou <strong>V\u00fdvojov\u00e9 poruchy mozku<\/strong> nebo <strong>Po\u0161kozen\u00ed mozku v d\u016fsledku vn\u011bj\u0161\u00edch vliv\u016f<\/strong>. Pat\u0159\u00ed mezi n\u011b mimo jin\u00e9 <strong>Nedostatek kysl\u00edku, krv\u00e1cen\u00ed do mozku, infekce<\/strong> (nap\u0159. zard\u011bnky v t\u011bhotenstv\u00ed nebo meningitida v d\u011btstv\u00ed), <strong>P\u0159\u00edli\u0161 n\u00edzk\u00e1 hladina cukru v krvi, z\u00e1va\u017en\u00e1 novorozeneck\u00e1 \u017eloutenka<\/strong> (nap\u0159. inkompatibilita s rhesus faktorem) a poran\u011bn\u00ed hlavy v dob\u011b porodu.<\/p><p>V mnoha p\u0159\u00edpadech <strong>Konkr\u00e9tn\u00ed p\u0159\u00ed\u010dinu nelze jednozna\u010dn\u011b ur\u010dit<\/strong>. Je v\u0161ak zn\u00e1mo, \u017ee <strong>P\u0159ed\u010dasn\u011b narozen\u00e9 d\u011bti, zejm\u00e9na s n\u00edzkou porodn\u00ed hmotnost\u00ed.<\/strong>, jsou posti\u017eeny v\u00fdrazn\u011b \u010dast\u011bji. Zvy\u0161uj\u00edc\u00ed se \u010detnost n\u011bkter\u00fdch forem d\u011btsk\u00e9 mozkov\u00e9 obrny se p\u0159i\u010d\u00edt\u00e1 mimo jin\u00e9 tomu, \u017ee se v sou\u010dasn\u00e9 dob\u011b <strong>M\u00edra p\u0159e\u017eit\u00ed p\u0159ed\u010dasn\u011b narozen\u00fdch d\u011bt\u00ed<\/strong> se v posledn\u00edch letech v\u00fdrazn\u011b zv\u00fd\u0161il.<\/p><p>Kojeneck\u00e1 mozkov\u00e1 obrna je <strong>Trval\u00fd stav<\/strong> a <strong>Nej\u010dast\u011bj\u0161\u00ed p\u0159\u00ed\u010dina t\u011blesn\u00e9ho posti\u017een\u00ed v d\u011btstv\u00ed<\/strong>. T\u00fdk\u00e1 se to nap\u0159\u00edklad <strong>jeden ze 400 \u017eiv\u011b narozen\u00fdch d\u011bt\u00ed<\/strong>. Existuj\u00ed tak\u00e9 <strong>Vz\u00e1cn\u00e1 d\u011bdi\u010dn\u00e1 onemocn\u011bn\u00ed<\/strong>, kter\u00e9 jsou sv\u00fdm vzhledem podobn\u00e9 mozkov\u00e9 obrn\u011b.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5e3e5a e-con-full e-flex e-con e-child\" data-id=\"f5e3e5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6da8c31 elementor-widget elementor-widget-heading\" data-id=\"6da8c31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">P\u0159\u00edznaky CEREBR\u00c1LN\u00cd PAR\u00c9ZY<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1a4483 e-grid e-con-full e-con e-child\" data-id=\"f1a4483\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0696d0 elementor-widget elementor-widget-text-editor\" data-id=\"b0696d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Hlavn\u00ed motorick\u00e9 p\u0159\u00edznaky<\/strong><\/p><p>\u00a0<\/p><p><strong>Poruchy pohybu a dr\u017een\u00ed t\u011bla<\/strong><\/p><p>Je naru\u0161ena kontrola pohyb\u016f a dr\u017een\u00ed t\u011bla. Stupe\u0148 z\u00e1va\u017enosti se pohybuje od sotva znateln\u00fdch abnormalit a\u017e po nejz\u00e1va\u017en\u011bj\u0161\u00ed omezen\u00ed.<\/p><p>\u00a0<\/p><p><strong>Spasticita a svalov\u00e1 ztuhlost<\/strong><\/p><p>Zv\u00fd\u0161en\u00e9 svalov\u00e9 nap\u011bt\u00ed m\u016f\u017ee v\u00e9st ke ztuhlosti, omezen\u00e9 pohyblivosti a bolesti.<\/p><p>\u00a0<\/p><p><strong>Zpo\u017ed\u011bn\u00ed pohybu<\/strong><\/p><p>Opo\u017ed\u011bn\u00fd v\u00fdvoj p\u0159i sezen\u00ed, plazen\u00ed, st\u00e1n\u00ed nebo ch\u016fzi. Spastick\u00e9 formy, jako je hemiplegie nebo diplegie, se \u010dasto objevuj\u00ed p\u0159ed druh\u00fdm rokem \u017eivota.<\/p><p>\u00a0<\/p><p><strong>Omezen\u00e1 jemn\u00e1 motorika<\/strong><\/p><p>pot\u00ed\u017ee s c\u00edlen\u00fdm pou\u017e\u00edv\u00e1n\u00edm rukou, nap\u0159. p\u0159i uchopov\u00e1n\u00ed, j\u00eddle nebo psan\u00ed.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c7a7c8 elementor-widget elementor-widget-text-editor\" data-id=\"9c7a7c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nemotorizovan\u00e9 <\/strong><strong>Hlavn\u00ed p\u0159\u00edznaky<\/strong><\/p><p>\u00a0<\/p><ul><li>Epileptick\u00e9 z\u00e1chvaty<\/li><\/ul><p>\u00a0<\/p><ul><li>Poruchy \u0159e\u010di a jazyka<\/li><\/ul><p>\u00a0<\/p><ul><li>Pot\u00ed\u017ee s polyk\u00e1n\u00edm a zv\u00fd\u0161en\u00e9 slin\u011bn\u00ed<\/li><\/ul><p>\u00a0<\/p><ul><li>Poruchy zraku (nap\u0159. \u0161ilh\u00e1n\u00ed) a sluchu.<\/li><\/ul><p>\u00a0<\/p><ul><li>Kognitivn\u00ed poruchy, od norm\u00e1ln\u00ed inteligence a\u017e po z\u00e1va\u017en\u00e1 omezen\u00ed.<\/li><\/ul><p>\u00a0<\/p><ul><li>pot\u00ed\u017ee s u\u010den\u00edm, \u010dasto ve spojen\u00ed s motorick\u00fdmi nebo zrakov\u00fdmi poruchami.<\/li><\/ul><p>\u00a0<\/p><ul><li>Sn\u00ed\u017een\u00fd cit pro dotek a bolest<\/li><\/ul><p>\u00a0<\/p><ul><li>Inkontinence a pomo\u010dov\u00e1n\u00ed<\/li><\/ul><p>\u00a0<\/p><ul><li>Psychick\u00fd a soci\u00e1ln\u00ed stres, zejm\u00e9na bez v\u010dasn\u00e9 podpory.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68c75b7 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"68c75b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/cp-hotline.com\/cs\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zjist\u011bte v\u00edce<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17bb8ff e-con-full e-flex e-con e-child\" data-id=\"17bb8ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa01d9b elementor-widget elementor-widget-heading\" data-id=\"fa01d9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BLOG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de6cf2e elementor-widget elementor-widget-shortcode\" data-id=\"de6cf2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    <div class=\"ph-slide-posts\">\n        <div class=\"ph-slick\">\n                                <div class=\"wb_ps_item\">\n                        <div class=\"wb_ps_single_item\">\n                            <div class=\"wb_ps_thumbnail\">\n                                <a href=\"https:\/\/cp-hotline.com\/cs\/zerebralparese-entwicklung-positiv-beeinflussen\/\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/2026\/01\/zerebralparese-uebungen-physiotherapie-1-1024x576.jpg\" title=\"Je mo\u017en\u00e9 pozitivn\u011b ovlivnit v\u00fdvoj d\u011btsk\u00e9 mozkov\u00e9 obrny?\" alt=\"Je mo\u017en\u00e9 pozitivn\u011b ovlivnit v\u00fdvoj d\u011btsk\u00e9 mozkov\u00e9 obrny?\">\n                                                                    <\/a>\n                            <\/div>\n                            <div class=\"wb_ps_content\">\n                                <div class=\"wb_ps_title\">\n                                    <h2><a href=\"https:\/\/cp-hotline.com\/cs\/zerebralparese-entwicklung-positiv-beeinflussen\/\">Je mo\u017en\u00e9 pozitivn\u011b ovlivnit v\u00fdvoj d\u011btsk\u00e9 mozkov\u00e9 obrny?<\/a><\/h2>\n                                <\/div>\n                                <div class=\"wb_ps_description\">\n                                    <div class=\"wb_ps_text\">\n                                        Viele Eltern von Kindern mit Zerebralparese stellen sich die Frage:\u2028\u201eGibt es M\u00f6glichkeiten, die Entwicklung unseres Kindes positiv zu beeinflussen?\u201c                                                                                <a class=\"wb_ps_readmore_link\" href=\"https:\/\/cp-hotline.com\/cs\/zerebralparese-entwicklung-positiv-beeinflussen\/\">P\u0159e\u010dt\u011bte si v\u00edce<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                <div class=\"wb_ps_item\">\n                        <div class=\"wb_ps_single_item\">\n                            <div class=\"wb_ps_thumbnail\">\n                                <a href=\"https:\/\/cp-hotline.com\/cs\/bewegung-training-zerebralparese\/\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/2026\/01\/bewegung-training-zerebralparese-giger-md-therapie-1024x683.jpg\" title=\"Pro\u010d je pohyb a tr\u00e9nink tak d\u016fle\u017eit\u00fd u d\u011btsk\u00e9 mozkov\u00e9 obrny?\" alt=\"Pro\u010d je pohyb a tr\u00e9nink tak d\u016fle\u017eit\u00fd u d\u011btsk\u00e9 mozkov\u00e9 obrny?\">\n                                                                    <\/a>\n                            <\/div>\n                            <div class=\"wb_ps_content\">\n                                <div class=\"wb_ps_title\">\n                                    <h2><a href=\"https:\/\/cp-hotline.com\/cs\/bewegung-training-zerebralparese\/\">Pro\u010d je pohyb a tr\u00e9nink tak d\u016fle\u017eit\u00fd u d\u011btsk\u00e9 mozkov\u00e9 obrny?<\/a><\/h2>\n                                <\/div>\n                                <div class=\"wb_ps_description\">\n                                    <div class=\"wb_ps_text\">\n                                        Bewegung spielt bei Kindern mit Zerebralparese eine zentrale Rolle. Sie ist nicht nur Teil der Therapie, sondern eine grundlegende Voraussetzung f\u00fcr Entwicklung, Lernen...                                                                                <a class=\"wb_ps_readmore_link\" href=\"https:\/\/cp-hotline.com\/cs\/bewegung-training-zerebralparese\/\">P\u0159e\u010dt\u011bte si v\u00edce<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                <div class=\"wb_ps_item\">\n                        <div class=\"wb_ps_single_item\">\n                            <div class=\"wb_ps_thumbnail\">\n                                <a href=\"https:\/\/cp-hotline.com\/cs\/fruehzeitige-foerderung-zerebralparese\/\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/2026\/01\/zerebralparese-fruehfoerderung-therapie-1024x683.jpg\" title=\"Pro\u010d je u d\u011btsk\u00e9 mozkov\u00e9 obrny z\u00e1sadn\u00ed v\u010dasn\u00e1 podpora\" alt=\"Pro\u010d je u d\u011btsk\u00e9 mozkov\u00e9 obrny z\u00e1sadn\u00ed v\u010dasn\u00e1 podpora\">\n                                                                    <\/a>\n                            <\/div>\n                            <div class=\"wb_ps_content\">\n                                <div class=\"wb_ps_title\">\n                                    <h2><a href=\"https:\/\/cp-hotline.com\/cs\/fruehzeitige-foerderung-zerebralparese\/\">Pro\u010d je u d\u011btsk\u00e9 mozkov\u00e9 obrny z\u00e1sadn\u00ed v\u010dasn\u00e1 podpora<\/a><\/h2>\n                                <\/div>\n                                <div class=\"wb_ps_description\">\n                                    <div class=\"wb_ps_text\">\n                                        Bei Zerebralparese stellt sich f\u00fcr viele Eltern fr\u00fch die Frage, wann und wie F\u00f6rderung beginnen sollte. Heute gilt als gesichert: Fr\u00fchzeitige, gezielte F\u00f6rderung...                                                                                <a class=\"wb_ps_readmore_link\" href=\"https:\/\/cp-hotline.com\/cs\/fruehzeitige-foerderung-zerebralparese\/\">P\u0159e\u010dt\u011bte si v\u00edce<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-691842a e-con-full e-flex e-con e-child\" data-id=\"691842a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b043be elementor-widget elementor-widget-heading\" data-id=\"7b043be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u010casto kladen\u00e9 ot\u00e1zky:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d78891 ph-fill-arrow elementor-widget elementor-widget-n-accordion\" data-id=\"9d78891\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;multiple&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:300,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Akordeon. Odkazy otev\u00edrejte kl\u00e1vesou Enter nebo mezern\u00edk, zav\u00edrejte kl\u00e1vesou Escape a navigujte pomoc\u00ed \u0161ipek.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1650\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1650\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Je mozkov\u00e1 obrna l\u00e9\u010diteln\u00e1? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1650\" class=\"elementor-element elementor-element-83b1c6c e-con-full e-flex e-con e-child\" data-id=\"83b1c6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1650\" class=\"elementor-element elementor-element-286ee26 e-flex e-con-boxed e-con e-child\" data-id=\"286ee26\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa90580 elementor-widget elementor-widget-text-editor\" data-id=\"aa90580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Heilbarkeit<\/strong> Zerebralparese ist eine lebenslange Erkrankung, die medizinisch nicht heilbar ist, da die Sch\u00e4digung des Gehirns nicht r\u00fcckg\u00e4ngig gemacht werden kann. Dennoch k\u00f6nnen gezielte Therapien wie Physiotherapie, Ergotherapie und Logop\u00e4die die Beweglichkeit und Koordination sp\u00fcrbar verbessern. Mit der richtigen Unterst\u00fctzung l\u00e4sst sich die Lebensqualit\u00e4t der Betroffenen erheblich steigern \u2013 CP ist damit zwar nicht heilbar, aber gut behandelbar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1651\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1651\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Jak\u00e9 jsou p\u0159\u00ed\u010diny CP? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1651\" class=\"elementor-element elementor-element-001cb50 e-con-full e-flex e-con e-child\" data-id=\"001cb50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1651\" class=\"elementor-element elementor-element-457a59d e-flex e-con-boxed e-con e-child\" data-id=\"457a59d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a26c3c elementor-widget elementor-widget-text-editor\" data-id=\"0a26c3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Zerebralparese entsteht durch eine Sch\u00e4digung des sich entwickelnden Gehirns, die vor der Geburt, w\u00e4hrend der Geburt oder in den ersten Lebensmonaten auftreten kann. M\u00f6gliche Ursachen sind Sauerstoffmangel, Infektionen oder Blutungen im Gehirn, die die normale Hirnentwicklung beeintr\u00e4chtigen. All diese Faktoren st\u00f6ren die Gehirnentwicklung und f\u00fchren zu den typischen dauerhaften Bewegungs- und Koordinationsst\u00f6rungen der Zerebralparese.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1652\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1652\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Zhor\u0161uje se CP v pr\u016fb\u011bhu \u017eivota? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1652\" class=\"elementor-element elementor-element-09d498b e-con-full e-flex e-con e-child\" data-id=\"09d498b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1652\" class=\"elementor-element elementor-element-4dee329 e-flex e-con-boxed e-con e-child\" data-id=\"4dee329\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-981991b elementor-widget elementor-widget-text-editor\" data-id=\"981991b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Gehirnsch\u00e4digung bei Zerebralparese ist nicht fortschreitend und verschlechtert sich mit der Zeit nicht weiter. Dennoch k\u00f6nnen sich Symptome ohne gezielte Therapie ver\u00e4ndern oder verst\u00e4rken, da Muskeln verk\u00fcrzen und Fehlhaltungen zunehmen k\u00f6nnen. Eine kontinuierliche und langfristige Behandlung ist daher entscheidend, um Symptome stabil zu halten und die Bewegungsf\u00e4higkeit bestm\u00f6glich zu erhalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1653\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1653\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Jak\u00e9 p\u0159\u00edznaky se mohou objevit u CP? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1653\" class=\"elementor-element elementor-element-c766742 e-con-full e-flex e-con e-child\" data-id=\"c766742\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1653\" class=\"elementor-element elementor-element-5cbfe40 e-flex e-con-boxed e-con e-child\" data-id=\"5cbfe40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff65c4c elementor-widget elementor-widget-text-editor\" data-id=\"ff65c4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Symptome der Zerebralparese sind sehr vielf\u00e4ltig und reichen von leichter Bewegungsunsicherheit bis hin zu ausgepr\u00e4gten motorischen Einschr\u00e4nkungen. H\u00e4ufig treten Muskelsteifheit, unkontrollierte Bewegungen, Koordinationsprobleme oder Haltungsst\u00f6rungen auf. Da kein Fall dem anderen gleicht, ist eine individuelle Diagnose und Therapie f\u00fcr jeden Betroffenen besonders wichtig.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1654\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1654\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Jak CP ovliv\u0148uje ka\u017edodenn\u00ed \u017eivot? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1654\" class=\"elementor-element elementor-element-6012f98 e-con-full e-flex e-con e-child\" data-id=\"6012f98\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1654\" class=\"elementor-element elementor-element-1ef0070 e-flex e-con-boxed e-con e-child\" data-id=\"1ef0070\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-057a80f elementor-widget elementor-widget-text-editor\" data-id=\"057a80f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Regelm\u00e4\u00dfige Therapien helfen, die Beweglichkeit zu erhalten, Schmerzen zu reduzieren und die Selbstst\u00e4ndigkeit zu f\u00f6rdern. Die Therapieziele werden individuell festgelegt und orientieren sich an den pers\u00f6nlichen F\u00e4higkeiten und Bed\u00fcrfnissen der Betroffenen. Ziel ist es, individuelle St\u00e4rken gezielt zu f\u00f6rdern, den Alltag zu erleichtern und eine m\u00f6glichst gro\u00dfe Teilhabe am gesellschaftlichen Leben zu erm\u00f6glichen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>ZEREBRALPARESE verstehen Kontaktieren Sie uns f\u00fcr mehr Infos! Ursachen von ZEREBRALPARESE Die infantile Zerebralparese entsteht durch Sch\u00e4digungen bestimmter Hirnregionen, die f\u00fcr die Steuerung von Bewegung, Haltung und Muskelspannung verantwortlich sind. Diese Sch\u00e4digungen treten w\u00e4hrend der Schwangerschaft, unter der Geburt oder kurz nach der Geburt auf, wenn sich das Gehirn noch in der Entwicklung befindet. M\u00f6gliche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-64817","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/pages\/64817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/comments?post=64817"}],"version-history":[{"count":104,"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/pages\/64817\/revisions"}],"predecessor-version":[{"id":66976,"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/pages\/64817\/revisions\/66976"}],"wp:attachment":[{"href":"https:\/\/cp-hotline.com\/cs\/wp-json\/wp\/v2\/media?parent=64817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}