{"id":64817,"date":"2025-12-25T09:53:46","date_gmt":"2025-12-25T08:53:46","guid":{"rendered":"https:\/\/cp-hotline.com\/?page_id=64817"},"modified":"2026-05-13T11:15:30","modified_gmt":"2026-05-13T09:15:30","slug":"zerebralparese","status":"publish","type":"page","link":"https:\/\/cp-hotline.com\/et\/zerebralparese\/","title":{"rendered":"CP"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"64817\" class=\"elementor elementor-64817\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6ba3d e-flex e-con-boxed e-con e-parent\" data-id=\"8b6ba3d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-99f8eaf e-con-full e-flex e-con e-child\" data-id=\"99f8eaf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4b8eb18 e-con-full e-flex e-con e-child\" data-id=\"4b8eb18\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b30f6d0 elementor-widget elementor-widget-image\" data-id=\"b30f6d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cp-hotline.com\/et\/kontakt\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/elementor\/thumbs\/zerebralparese-kind-mutter-rollstuhl-verstehen-scaled-rnchn8cf1rpwsobqbdt7befejjzsatw9cp9vqhsw4k.jpg\" title=\"Happy,Mother,Hugging,Her,Son,With,Cerebral,Palsy,In,Wheelchair\" alt=\"Happy,Mother,Hugging,Her,Son,With,Cerebral,Palsy,In,Wheelchair\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ab4a57 e-con-full e-flex e-con e-child\" data-id=\"2ab4a57\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ecb9a9 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7ecb9a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">ZEREBRALPARESE verstehen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4758a0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e4758a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/cp-hotline.com\/et\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie uns f\u00fcr mehr Infos!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83d7521 e-con-full e-flex e-con e-child\" data-id=\"83d7521\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf4e31 elementor-widget elementor-widget-heading\" data-id=\"bbf4e31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ursachen von ZEREBRALPARESE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-737b9d9 elementor-widget elementor-widget-text-editor\" data-id=\"737b9d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die infantile Zerebralparese entsteht durch <strong>Sch\u00e4digungen bestimmter Hirnregionen<\/strong>, die f\u00fcr die Steuerung von <strong>Bewegung, Haltung und Muskelspannung<\/strong> verantwortlich sind. Diese Sch\u00e4digungen treten <strong>w\u00e4hrend der Schwangerschaft, unter der Geburt oder kurz nach der Geburt<\/strong> auf, wenn sich das Gehirn noch in der Entwicklung befindet.<\/p><p>M\u00f6gliche Ursachen sind <strong>Entwicklungsst\u00f6rungen des Gehirns<\/strong> oder <strong>Hirnsch\u00e4digungen durch \u00e4ussere Einfl\u00fcsse<\/strong>. Dazu z\u00e4hlen unter anderem <strong>Sauerstoffmangel, Hirnblutungen, Infektionen<\/strong> (z. B. R\u00f6teln w\u00e4hrend der Schwangerschaft oder Meningitis im S\u00e4uglingsalter), <strong>zu niedriger Blutzucker, schwere Neugeborenengelbsucht<\/strong> (z. B. bei Rhesusfaktor-Inkompatibilit\u00e4t) sowie Kopfverletzungen rund um die Geburt.<\/p><p>In vielen F\u00e4llen l\u00e4sst sich die <strong>konkrete Ursache nicht eindeutig feststellen<\/strong>. Bekannt ist jedoch, dass <strong>Fr\u00fchgeborene, insbesondere mit niedrigem Geburtsgewicht<\/strong>, deutlich h\u00e4ufiger betroffen sind. Die steigende H\u00e4ufigkeit bestimmter Formen der Zerebralparese wird unter anderem darauf zur\u00fcckgef\u00fchrt, dass die <strong>\u00dcberlebensrate von Fr\u00fchgeborenen<\/strong> in den letzten Jahren deutlich zugenommen hat.<\/p><p>Die infantile Zerebralparese ist ein <strong>Dauerzustand<\/strong> und die <strong>h\u00e4ufigste Ursache f\u00fcr k\u00f6rperliche Behinderungen im Kindesalter<\/strong>. Sie betrifft etwa <strong>eine von 400 Lebendgeburten<\/strong>. Es existieren zudem <strong>seltene Erbkrankheiten<\/strong>, die im Erscheinungsbild der Zerebralparese \u00e4hneln.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5e3e5a e-con-full e-flex e-con e-child\" data-id=\"f5e3e5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6da8c31 elementor-widget elementor-widget-heading\" data-id=\"6da8c31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Symptome der ZEREBRALPARESE<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1a4483 e-grid e-con-full e-con e-child\" data-id=\"f1a4483\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0696d0 elementor-widget elementor-widget-text-editor\" data-id=\"b0696d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Motorische Hauptsymptome<\/strong><\/p><p>\u00a0<\/p><p><strong>St\u00f6rungen von Bewegung und Haltung<\/strong><\/p><p>Die Kontrolle von Bewegungen und K\u00f6rperhaltung ist beeintr\u00e4chtigt. Der Schweregrad reicht von kaum wahrnehmbaren Auff\u00e4lligkeiten bis hin zu schwersten Einschr\u00e4nkungen.<\/p><p>\u00a0<\/p><p><strong>Spastik und Muskelsteifheit<\/strong><\/p><p>Erh\u00f6hte Muskelspannung kann zu Steifheit, eingeschr\u00e4nkter Beweglichkeit und Schmerzen f\u00fchren.<\/p><p>\u00a0<\/p><p><strong>Bewegungsverz\u00f6gerungen<\/strong><\/p><p>Entwicklungsverz\u00f6gerungen beim Sitzen, Krabbeln, Stehen oder Gehen. Spastische Formen wie Hemiplegie oder Diplegie zeigen sich h\u00e4ufig vor dem zweiten Lebensjahr.<\/p><p>\u00a0<\/p><p><strong>Eingeschr\u00e4nkte Feinmotorik<\/strong><\/p><p>Schwierigkeiten beim gezielten Gebrauch der H\u00e4nde, z. B. beim Greifen, Essen oder Schreiben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c7a7c8 elementor-widget elementor-widget-text-editor\" data-id=\"9c7a7c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Nicht motorische <\/strong><strong>Hauptsymptome<\/strong><\/p><p>\u00a0<\/p><ul><li>Epileptische Anf\u00e4lle<\/li><\/ul><p>\u00a0<\/p><ul><li>Sprach- und Sprechst\u00f6rungen<\/li><\/ul><p>\u00a0<\/p><ul><li>Schluckbeschwerden und vermehrter Speichelfluss<\/li><\/ul><p>\u00a0<\/p><ul><li>Sehst\u00f6rungen (z. B. Schielen) und H\u00f6rst\u00f6rungen<\/li><\/ul><p>\u00a0<\/p><ul><li>Kognitive Beeintr\u00e4chtigungen, von normaler Intelligenz bis zu schweren Einschr\u00e4nkungen<\/li><\/ul><p>\u00a0<\/p><ul><li>Lernschwierigkeiten, h\u00e4ufig im Zusammenhang mit motorischen oder visuellen Einschr\u00e4nkungen<\/li><\/ul><p>\u00a0<\/p><ul><li>Verminderte Ber\u00fchrungs- und Schmerzempfindung<\/li><\/ul><p>\u00a0<\/p><ul><li>Inkontinenz und Bettn\u00e4ssen<\/li><\/ul><p>\u00a0<\/p><ul><li>Psychische und soziale Belastungen, insbesondere ohne fr\u00fchzeitige Unterst\u00fctzung<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68c75b7 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"68c75b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-bob\" href=\"https:\/\/cp-hotline.com\/et\/kontakt\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Lisateave<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17bb8ff e-con-full e-flex e-con e-child\" data-id=\"17bb8ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa01d9b elementor-widget elementor-widget-heading\" data-id=\"fa01d9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BLOG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de6cf2e elementor-widget elementor-widget-shortcode\" data-id=\"de6cf2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    <div class=\"ph-slide-posts\">\n        <div class=\"ph-slick\">\n                                <div class=\"wb_ps_item\">\n                        <div class=\"wb_ps_single_item\">\n                            <div class=\"wb_ps_thumbnail\">\n                                <a href=\"https:\/\/cp-hotline.com\/et\/zerebralparese-entwicklung-positiv-beeinflussen\/\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/2026\/01\/zerebralparese-uebungen-physiotherapie-1-1024x576.jpg\" title=\"Kas on v\u00f5imalik m\u00f5jutada positiivselt tserebraalparal\u00fc\u00fcsi arengut?\" alt=\"Kas on v\u00f5imalik m\u00f5jutada positiivselt tserebraalparal\u00fc\u00fcsi arengut?\">\n                                                                    <\/a>\n                            <\/div>\n                            <div class=\"wb_ps_content\">\n                                <div class=\"wb_ps_title\">\n                                    <h2><a href=\"https:\/\/cp-hotline.com\/et\/zerebralparese-entwicklung-positiv-beeinflussen\/\">Kas on v\u00f5imalik m\u00f5jutada positiivselt tserebraalparal\u00fc\u00fcsi arengut?<\/a><\/h2>\n                                <\/div>\n                                <div class=\"wb_ps_description\">\n                                    <div class=\"wb_ps_text\">\n                                        Viele Eltern von Kindern mit Zerebralparese stellen sich die Frage:\u2028\u201eGibt es M\u00f6glichkeiten, die Entwicklung unseres Kindes positiv zu beeinflussen?\u201c                                                                                <a class=\"wb_ps_readmore_link\" href=\"https:\/\/cp-hotline.com\/et\/zerebralparese-entwicklung-positiv-beeinflussen\/\">Read more<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                <div class=\"wb_ps_item\">\n                        <div class=\"wb_ps_single_item\">\n                            <div class=\"wb_ps_thumbnail\">\n                                <a href=\"https:\/\/cp-hotline.com\/et\/bewegung-training-zerebralparese\/\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/2026\/01\/bewegung-training-zerebralparese-giger-md-therapie-1024x683.jpg\" title=\"Miks liikumine ja treening on tserebraalparal\u00fc\u00fcsi puhul nii olulised\" alt=\"Miks liikumine ja treening on tserebraalparal\u00fc\u00fcsi puhul nii olulised\">\n                                                                    <\/a>\n                            <\/div>\n                            <div class=\"wb_ps_content\">\n                                <div class=\"wb_ps_title\">\n                                    <h2><a href=\"https:\/\/cp-hotline.com\/et\/bewegung-training-zerebralparese\/\">Miks liikumine ja treening on tserebraalparal\u00fc\u00fcsi puhul nii olulised<\/a><\/h2>\n                                <\/div>\n                                <div class=\"wb_ps_description\">\n                                    <div class=\"wb_ps_text\">\n                                        Bewegung spielt bei Kindern mit Zerebralparese eine zentrale Rolle. Sie ist nicht nur Teil der Therapie, sondern eine grundlegende Voraussetzung f\u00fcr Entwicklung, Lernen...                                                                                <a class=\"wb_ps_readmore_link\" href=\"https:\/\/cp-hotline.com\/et\/bewegung-training-zerebralparese\/\">Read more<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                <div class=\"wb_ps_item\">\n                        <div class=\"wb_ps_single_item\">\n                            <div class=\"wb_ps_thumbnail\">\n                                <a href=\"https:\/\/cp-hotline.com\/et\/fruehzeitige-foerderung-zerebralparese\/\">\n                                                                            <img decoding=\"async\" src=\"https:\/\/cp-hotline.com\/wp-content\/uploads\/2026\/01\/zerebralparese-fruehfoerderung-therapie-1024x683.jpg\" title=\"Miks varajane toetus on tserebraalparal\u00fc\u00fcsi puhul \u00fclioluline\" alt=\"Miks varajane toetus on tserebraalparal\u00fc\u00fcsi puhul \u00fclioluline\">\n                                                                    <\/a>\n                            <\/div>\n                            <div class=\"wb_ps_content\">\n                                <div class=\"wb_ps_title\">\n                                    <h2><a href=\"https:\/\/cp-hotline.com\/et\/fruehzeitige-foerderung-zerebralparese\/\">Miks varajane toetus on tserebraalparal\u00fc\u00fcsi puhul \u00fclioluline<\/a><\/h2>\n                                <\/div>\n                                <div class=\"wb_ps_description\">\n                                    <div class=\"wb_ps_text\">\n                                        Bei Zerebralparese stellt sich f\u00fcr viele Eltern fr\u00fch die Frage, wann und wie F\u00f6rderung beginnen sollte. Heute gilt als gesichert: Fr\u00fchzeitige, gezielte F\u00f6rderung...                                                                                <a class=\"wb_ps_readmore_link\" href=\"https:\/\/cp-hotline.com\/et\/fruehzeitige-foerderung-zerebralparese\/\">Read more<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-691842a e-con-full e-flex e-con e-child\" data-id=\"691842a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b043be elementor-widget elementor-widget-heading\" data-id=\"7b043be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Korduma kippuvad k\u00fcsimused:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d78891 ph-fill-arrow elementor-widget elementor-widget-n-accordion\" data-id=\"9d78891\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;multiple&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:300,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Akordion. Avage lingid Enteri v\u00f5i t\u00fchikuga, sulgege Escape&#039;iga ja navigeerige nooleklahvidega.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1650\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1650\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Ist Zerebralparese heilbar? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1650\" class=\"elementor-element elementor-element-83b1c6c e-con-full e-flex e-con e-child\" data-id=\"83b1c6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1650\" class=\"elementor-element elementor-element-286ee26 e-flex e-con-boxed e-con e-child\" data-id=\"286ee26\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa90580 elementor-widget elementor-widget-text-editor\" data-id=\"aa90580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Heilbarkeit<\/strong> Zerebralparese ist eine lebenslange Erkrankung, die medizinisch nicht heilbar ist, da die Sch\u00e4digung des Gehirns nicht r\u00fcckg\u00e4ngig gemacht werden kann. Dennoch k\u00f6nnen gezielte Therapien wie Physiotherapie, Ergotherapie und Logop\u00e4die die Beweglichkeit und Koordination sp\u00fcrbar verbessern. Mit der richtigen Unterst\u00fctzung l\u00e4sst sich die Lebensqualit\u00e4t der Betroffenen erheblich steigern \u2013 CP ist damit zwar nicht heilbar, aber gut behandelbar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1651\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1651\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Welche Ursachen hat CP? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1651\" class=\"elementor-element elementor-element-001cb50 e-con-full e-flex e-con e-child\" data-id=\"001cb50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1651\" class=\"elementor-element elementor-element-457a59d e-flex e-con-boxed e-con e-child\" data-id=\"457a59d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a26c3c elementor-widget elementor-widget-text-editor\" data-id=\"0a26c3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Zerebralparese entsteht durch eine Sch\u00e4digung des sich entwickelnden Gehirns, die vor der Geburt, w\u00e4hrend der Geburt oder in den ersten Lebensmonaten auftreten kann. M\u00f6gliche Ursachen sind Sauerstoffmangel, Infektionen oder Blutungen im Gehirn, die die normale Hirnentwicklung beeintr\u00e4chtigen. All diese Faktoren st\u00f6ren die Gehirnentwicklung und f\u00fchren zu den typischen dauerhaften Bewegungs- und Koordinationsst\u00f6rungen der Zerebralparese.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1652\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1652\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Verschlechtert sich CP im Laufe des Lebens? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1652\" class=\"elementor-element elementor-element-09d498b e-con-full e-flex e-con e-child\" data-id=\"09d498b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1652\" class=\"elementor-element elementor-element-4dee329 e-flex e-con-boxed e-con e-child\" data-id=\"4dee329\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-981991b elementor-widget elementor-widget-text-editor\" data-id=\"981991b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Gehirnsch\u00e4digung bei Zerebralparese ist nicht fortschreitend und verschlechtert sich mit der Zeit nicht weiter. Dennoch k\u00f6nnen sich Symptome ohne gezielte Therapie ver\u00e4ndern oder verst\u00e4rken, da Muskeln verk\u00fcrzen und Fehlhaltungen zunehmen k\u00f6nnen. Eine kontinuierliche und langfristige Behandlung ist daher entscheidend, um Symptome stabil zu halten und die Bewegungsf\u00e4higkeit bestm\u00f6glich zu erhalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1653\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1653\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Welche Symptome k\u00f6nnen bei CP auftreten? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1653\" class=\"elementor-element elementor-element-c766742 e-con-full e-flex e-con e-child\" data-id=\"c766742\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1653\" class=\"elementor-element elementor-element-5cbfe40 e-flex e-con-boxed e-con e-child\" data-id=\"5cbfe40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff65c4c elementor-widget elementor-widget-text-editor\" data-id=\"ff65c4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Symptome der Zerebralparese sind sehr vielf\u00e4ltig und reichen von leichter Bewegungsunsicherheit bis hin zu ausgepr\u00e4gten motorischen Einschr\u00e4nkungen. H\u00e4ufig treten Muskelsteifheit, unkontrollierte Bewegungen, Koordinationsprobleme oder Haltungsst\u00f6rungen auf. Da kein Fall dem anderen gleicht, ist eine individuelle Diagnose und Therapie f\u00fcr jeden Betroffenen besonders wichtig.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1654\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1654\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Wie wirkt sich CP auf den Alltag aus? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.0002 18.4825L12.965 3.3491L24.6799 18.6691\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"21\" viewbox=\"0 0 27 21\" fill=\"none\"><path d=\"M2.00017 2.00014L12.7151 17.2088L24.6794 2.1868\" stroke=\"black\" stroke-width=\"4\" stroke-linecap=\"round\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1654\" class=\"elementor-element elementor-element-6012f98 e-con-full e-flex e-con e-child\" data-id=\"6012f98\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1654\" class=\"elementor-element elementor-element-1ef0070 e-flex e-con-boxed e-con e-child\" data-id=\"1ef0070\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-057a80f elementor-widget elementor-widget-text-editor\" data-id=\"057a80f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Regelm\u00e4\u00dfige Therapien helfen, die Beweglichkeit zu erhalten, Schmerzen zu reduzieren und die Selbstst\u00e4ndigkeit zu f\u00f6rdern. Die Therapieziele werden individuell festgelegt und orientieren sich an den pers\u00f6nlichen F\u00e4higkeiten und Bed\u00fcrfnissen der Betroffenen. Ziel ist es, individuelle St\u00e4rken gezielt zu f\u00f6rdern, den Alltag zu erleichtern und eine m\u00f6glichst gro\u00dfe Teilhabe am gesellschaftlichen Leben zu erm\u00f6glichen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>ZEREBRALPARESE verstehen Kontaktieren Sie uns f\u00fcr mehr Infos! Ursachen von ZEREBRALPARESE Die infantile Zerebralparese entsteht durch Sch\u00e4digungen bestimmter Hirnregionen, die f\u00fcr die Steuerung von Bewegung, Haltung und Muskelspannung verantwortlich sind. Diese Sch\u00e4digungen treten w\u00e4hrend der Schwangerschaft, unter der Geburt oder kurz nach der Geburt auf, wenn sich das Gehirn noch in der Entwicklung befindet. M\u00f6gliche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-64817","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/pages\/64817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/comments?post=64817"}],"version-history":[{"count":104,"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/pages\/64817\/revisions"}],"predecessor-version":[{"id":66976,"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/pages\/64817\/revisions\/66976"}],"wp:attachment":[{"href":"https:\/\/cp-hotline.com\/et\/wp-json\/wp\/v2\/media?parent=64817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}